{"id":42093,"date":"2026-05-13T17:14:27","date_gmt":"2026-05-13T20:14:27","guid":{"rendered":"https:\/\/cajamar.sp.gov.br\/noticias\/?p=42093"},"modified":"2026-05-13T17:14:46","modified_gmt":"2026-05-13T20:14:46","slug":"campeonato-veretano-veretnissimo-e-master-2026-tera-congresso-tecnico-em-cajamar","status":"publish","type":"post","link":"https:\/\/cajamar.sp.gov.br\/noticias\/2026\/05\/13\/campeonato-veretano-veretnissimo-e-master-2026-tera-congresso-tecnico-em-cajamar\/","title":{"rendered":"Campeonato Veretano, Veretn\u00edssimo e Master 2026 ter\u00e1 congresso t\u00e9cnico em Cajamar"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1076\" height=\"672\" src=\"https:\/\/cajamar.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/2\/2026\/05\/whatsapp-image-2026-05-13-at-17-09-08.jpeg\" alt=\"\" class=\"wp-image-42094\" srcset=\"https:\/\/cajamar.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/2\/2026\/05\/whatsapp-image-2026-05-13-at-17-09-08.jpeg 1076w, https:\/\/cajamar.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/2\/2026\/05\/whatsapp-image-2026-05-13-at-17-09-08-768x480.jpeg 768w\" sizes=\"(max-width: 1076px) 100vw, 1076px\" \/><\/figure>\n\n\n\n<p>A Prefeitura de Cajamar, por meio da Secretaria Municipal de Esportes e Lazer, realizar\u00e1 o Congresso T\u00e9cnico dos Campeonatos Veterano, Veteran\u00edssimo e Master de Futebol 2026.<\/p>\n\n\n\n<p>O encontro reunir\u00e1 dirigentes, representantes das equipes e atletas para defini\u00e7\u00e3o dos detalhes da competi\u00e7\u00e3o, incluindo o n\u00famero de participantes, forma de disputa e o sorteio de atletas para forma\u00e7\u00e3o das equipes.<\/p>\n\n\n\n<p>Os congressos acontecer\u00e3o nos distritos de Jordan\u00e9sia e Polvilho. Confira a programa\u00e7\u00e3o:<\/p>\n\n\n\n<p>\ud83d\udcc5 <strong>14 de maio de 2026 (quinta-feira)<\/strong><br>\ud83d\udd56 A partir das 19h00<br>\ud83d\udccd PEC \u2013 Pra\u00e7a dos Esportes e Cultura Irineu L\u00facio Rodrigues<br>\ud83d\udccc Rua Constantino Francisco de Almeida, n\u00ba 3671 \u2013 465 \u2013 Jardim Santana<\/p>\n\n\n\n<p>\ud83d\udcc5 <strong>15 de maio de 2026 (sexta-feira)<\/strong><br>\ud83d\udd56 A partir das 19h00<br>\ud83d\udccd Gin\u00e1sio de Esportes \u201cPrefeito Manoel \u00c1lvares\u201d<br>\ud83d\udccc Avenida Joaquim Pereira Barbosa, n\u00ba 827 \u2013 Jordan\u00e9sia<\/p>\n\n\n\n<p>A Secretaria de Esportes refor\u00e7a a import\u00e2ncia da participa\u00e7\u00e3o dos representantes das equipes para alinhamento das informa\u00e7\u00f5es e organiza\u00e7\u00e3o do campeonato, que promete movimentar o futebol cajamarense em mais uma grande edi\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encontro reunir\u00e1 representantes das equipes para defini\u00e7\u00e3o da competi\u00e7\u00e3o e sorteio de atletas<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,1],"tags":[],"posicao":[28],"class_list":["post-42093","post","type-post","status-publish","format-standard","hentry","category-esportes-e-lazer","category-noticias","posicao-destaque"],"_links":{"self":[{"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posts\/42093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/comments?post=42093"}],"version-history":[{"count":1,"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posts\/42093\/revisions"}],"predecessor-version":[{"id":42095,"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posts\/42093\/revisions\/42095"}],"wp:attachment":[{"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/media?parent=42093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/categories?post=42093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/tags?post=42093"},{"taxonomy":"posicao","embeddable":true,"href":"https:\/\/cajamar.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posicao?post=42093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}